{"id":392,"date":"2022-08-09T16:00:54","date_gmt":"2022-08-09T21:00:54","guid":{"rendered":"https:\/\/futswap.se\/?page_id=392"},"modified":"2025-05-29T11:05:48","modified_gmt":"2025-05-29T16:05:48","slug":"home","status":"publish","type":"page","link":"https:\/\/futswap.se\/sv","title":{"rendered":"Futswap\u00ae &#8211; Global Financial Solutions &#038; Futcard Services"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"392\" class=\"elementor elementor-392\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b8d5be elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4b8d5be\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-948277b\" data-id=\"948277b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d87331 elementor-widget elementor-widget-heading\" data-id=\"7d87331\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Smarta finansiella l\u00f6sningar <span style=\"color:var(--e-global-color-primary)\">f\u00f6r dig att flytta dina tillg\u00e5ngar runt om i v\u00e4rlden<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec6ab1 elementor-widget elementor-widget-heading\" data-id=\"aec6ab1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">En plattform designad f\u00f6r dem som tror att pengar inte har n\u00e5gra gr\u00e4nser.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45436c9 elementor-tablet-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"45436c9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/login.futswap.io\/sign-up\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ans\u00f6k nu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e800e3c\" data-id=\"e800e3c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13c96d2 elementor-widget__width-initial e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"13c96d2\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-15,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"268\" height=\"458\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-5.jpg\" class=\"attachment-full size-full wp-image-10132\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-5.jpg 268w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-5-176x300.jpg 176w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-5-7x12.jpg 7w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-5-150x256.jpg 150w\" sizes=\"(max-width: 268px) 100vw, 268px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba36ddb elementor-widget__width-initial e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ba36ddb\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:200,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"266\" height=\"456\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-sweden-wall.jpg\" class=\"attachment-full size-full wp-image-10130\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-sweden-wall.jpg 266w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-sweden-wall-175x300.jpg 175w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-sweden-wall-7x12.jpg 7w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-sweden-wall-150x257.jpg 150w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a67387e elementor-widget__width-initial elementor-absolute e-transform elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a67387e\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:-50,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:500,&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"266\" height=\"438\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-6-1.png\" class=\"attachment-full size-full wp-image-10134\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-6-1.png 266w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-6-1-182x300.png 182w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-6-1-7x12.png 7w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-hero-home-sweden-6-1-150x247.png 150w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c81c18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c81c18\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3a3c5d\" data-id=\"a3a3c5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b8b3dc2 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b8b3dc2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b4152ba\" data-id=\"b4152ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c040456 elementor-position-left elementor-widget__width-initial elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c040456\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"68\" height=\"36\" viewbox=\"0 0 68 36\" fill=\"none\"><path d=\"M5.92308 16.9712C3.52564 16.0719 2.67949 15.1727 2.67949 13.9137C2.67949 12.4748 3.80769 11.3957 5.64103 11.3957C7.61538 11.3957 8.32051 12.6547 8.32051 14.2734H10.7179C10.5769 11.9353 9.44872 9.77698 7.19231 9.05755V6H3.94872V9.05755C1.83333 9.59712 0.141026 11.3957 0.141026 13.9137C0.141026 17.1511 2.25641 18.7698 5.21795 19.6691C7.89744 20.5683 8.46154 21.6475 8.46154 23.0863C8.46154 23.9856 7.89744 25.6043 5.5 25.6043C3.24359 25.6043 2.39744 24.3453 2.25641 22.7266H0C0.141026 25.7842 1.97436 27.4029 3.94872 27.9424V31H7.19231V27.9424C9.30769 27.4029 11 25.7842 11 23.0863C11 19.1295 8.32051 17.6906 5.92308 16.9712Z\" fill=\"white\"><\/path><path d=\"M64.6667 30C66.1818 30 67.697 28.7308 68 26.6154L66.4848 25.3462C66.1818 26.6154 65.5758 27.4615 64.6667 27.4615H60.4242C61.0303 26.1923 61.6364 24.5 61.6364 22.8077C61.6364 22.3846 61.6364 21.9615 61.6364 21.5385H64.6667V19.4231H61.0303C60.4242 17.7308 59.5152 16.4615 59.5152 14.7692C59.5152 12.6538 60.7273 10.5385 62.5455 10.5385C63.7576 10.5385 64.9697 11.8077 65.2727 13.0769L66.7879 12.2308C66.1818 9.69231 64.3636 8 62.5455 8C60.1212 8 58 10.9615 58 14.3462C58 16.4615 58.6061 17.7308 59.2121 19H58V21.5385H60.1212C60.1212 21.9615 60.1212 22.3846 60.1212 22.8077C60.1212 26.1923 58 27.4615 58 27.4615V30H64.6667Z\" fill=\"white\"><\/path><path d=\"M40.6667 30.5217C35.7333 30.5217 30.8 28.1739 29.1556 24.2609H40.6667V20.3478H27.5111C27.5111 19.5652 27.5111 18.7826 27.5111 18C27.5111 17.2174 27.5111 16.4348 27.5111 15.6522H40.6667V12.5217H29.1556C30.8 7.82609 35.7333 5.47826 40.6667 5.47826C43.9556 5.47826 47.2444 6.26087 49.7111 8.60869L53 5.47826C49.7111 2.34783 45.6 0 40.6667 0C32.4444 0 25.8667 4.69565 23.4 11.7391H16V15.6522H22.5778C22.5778 16.4348 22.5778 17.2174 22.5778 18C22.5778 18.7826 22.5778 19.5652 22.5778 20.3478H16V24.2609H23.4C25.8667 30.5217 32.4444 36 40.6667 36C45.6 36 49.7111 34.4348 53 31.3044L49.7111 27.3913C47.2444 29.7391 43.9556 30.5217 40.6667 30.5217Z\" fill=\"#8081FF\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOpen your operational account online\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c271b62 elementor-align-right elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"c271b62\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/operational-account\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visa mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e9cb45e\" data-id=\"e9cb45e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbed760 elementor-position-left elementor-widget__width-initial elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"fbed760\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51\" height=\"28\" viewbox=\"0 0 51 28\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 13.251H17.6895V10.8593H0V13.251ZM45.6565 21.3093C45.6565 21.1153 45.5057 20.9645 45.3118 20.9645H32.6641C32.4702 20.9645 32.3194 21.1153 32.3194 21.3093V21.9772C32.3194 22.1711 32.4702 22.3219 32.6641 22.3219H45.3118C45.5057 22.3219 45.6565 22.1711 45.6565 21.9772V21.3093ZM10.73 0.387833L1.42205 5.75285C0.538657 6.26996 0 7.218 0 8.23067V8.46768H17.6895C18.3359 8.46768 18.9176 8.70469 19.3916 9.17871C19.8441 9.63118 20.0811 10.1914 20.0811 10.8593V23.076L22.8821 21.4601C23.7655 20.943 24.3257 19.9949 24.3257 18.9607V8.23067C24.3257 7.218 23.7871 6.26996 22.8821 5.75285L13.5957 0.366286C13.1432 0.129278 12.6692 0 12.1521 0C11.6565 0 11.161 0.129278 10.73 0.387833ZM20.4043 0.818758H48.5222C49.8796 0.818758 51 1.91762 51 3.29658V23.9163C51 25.2738 49.8796 26.3942 48.5222 26.3942H20.4043L24.3473 24.1103C26.2003 23.033 27.3422 21.0507 27.3422 18.8961V8.29531C27.3422 6.14068 26.2003 4.15843 24.3473 3.08112L20.4043 0.818758ZM0 15.6426V18.9607C0 19.9949 0.560203 20.943 1.4436 21.4385L10.73 26.8035C11.161 27.0621 11.6565 27.1914 12.1736 27.1914C12.6692 27.1914 13.1648 27.0621 13.6172 26.8035L17.711 24.4335V15.6426H0Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAns\u00f6k om ditt Futcard: framtidens kort\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76347cc elementor-align-right elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"76347cc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/fotbollskort\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visa mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9d05ba5\" data-id=\"9d05ba5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ace8a2 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"9ace8a2\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"75\" height=\"75\" viewbox=\"0 0 75 75\"><g><path d=\"M72.8906 30.1564C71.6992 29.2384 70.3125 28.7892 68.8086 28.7306C66.0938 28.6134 63.8281 29.7071 61.8164 31.4064C61.1719 31.9532 60.5859 32.5782 59.9609 33.1642C59.7461 32.9689 59.5508 32.7735 59.3555 32.5978C55.332 28.8282 50.5469 26.6603 45.0586 26.5626C38.125 26.4259 31.1914 26.6017 24.2578 26.6212C24.043 26.6212 23.7109 26.504 23.6133 26.3282C20.5859 21.8165 15.1172 20.8595 10.5859 22.129C8.73047 22.6564 8.20313 24.4923 9.47266 25.8985C10.8594 27.422 11.6602 29.2189 12.207 31.172C12.2656 31.3868 12.168 31.7579 11.9922 31.9142C9.66797 33.9845 7.83203 36.4259 6.50391 39.2384C6.40625 39.4532 6.05469 39.6681 5.80078 39.6681C4.84375 39.7267 3.88672 39.7462 2.94922 39.6681C1.58203 39.59 0.585938 40.0392 0 41.3087V55.6642C0.585938 57.0314 1.60156 57.5978 3.08594 57.4415C3.71094 57.3634 4.35547 57.5001 4.98047 57.422C5.95703 57.2853 6.44531 57.6759 6.89453 58.5743C9.23828 63.2228 12.8711 66.5822 17.6367 68.6915C18.0859 68.8868 18.2031 69.1017 18.0859 69.5704C17.8906 70.4298 17.793 71.3087 17.6367 72.1681C17.3438 73.8478 18.2617 75.0001 19.9609 75.0197C22.7539 75.0197 25.5273 75.0197 28.3203 75.0197C29.7266 75.0197 30.5078 74.3165 30.7617 72.9103C30.8984 72.1486 31.0352 71.4064 31.1523 70.6642H39.1992C39.2383 70.7423 39.2773 70.7814 39.2969 70.8204C39.4336 71.5626 39.5508 72.3048 39.6875 73.047C39.9023 74.297 40.7422 75.0197 42.0117 75.0197C44.8633 75.0392 47.7148 75.0392 50.5859 75.0197C52.0898 75.0197 53.0664 73.8282 52.8125 72.3243C52.6563 71.3868 52.5195 70.4493 52.3242 69.5118C52.2461 69.1017 52.3242 68.8868 52.7344 68.7306C53.3008 68.5157 53.8477 68.2423 54.3945 67.9493C62.6953 63.6329 67.3633 54.4142 65.9375 45.1954C65.5078 42.3829 64.5117 39.7853 63.1055 37.3243C62.9883 37.1095 62.8906 36.7189 62.9883 36.5821C64.0625 35.1954 65.2734 33.965 66.9727 33.3595C67.9492 33.0079 68.9258 32.9884 69.9024 33.4376C70.6445 33.7892 70.8008 34.3165 70.332 34.9806C70.1172 35.2931 69.7852 35.5275 69.4922 35.7618C68.6133 36.4845 68.3789 37.7345 68.9649 38.6525C69.5508 39.59 70.7422 40.0001 71.7188 39.4923C75.0781 37.715 76.4844 32.9298 72.8906 30.1564ZM49.7461 65.1759C47.8125 65.8595 47.4414 66.465 47.7344 68.4962C47.832 69.1603 47.9492 69.8439 48.0664 70.547H43.7695C43.6328 69.8243 43.4961 69.0626 43.3789 68.3009C43.125 66.8556 42.3438 66.1915 40.8789 66.1915C37.1094 66.1915 33.3594 66.1915 29.6094 66.1915C28.125 66.1915 27.3633 66.8556 27.1094 68.3009C26.9922 69.0431 26.8555 69.7853 26.7188 70.547H22.4023C22.5391 69.7072 22.6563 68.9064 22.8125 68.1251C23.0664 66.6603 22.5586 65.7618 21.0938 65.2736C16.4844 63.7111 13.0859 60.7228 10.8398 56.4259C10.5078 55.7814 10.2344 55.0978 9.96094 54.4142C9.53125 53.3595 8.78906 52.8321 7.65625 52.8517C6.66016 52.8517 5.66406 52.8517 4.64844 52.8321C4.60938 52.8321 4.55078 52.8126 4.47266 52.7736V44.0626H7.34375C8.90625 44.0626 9.47266 43.672 10.0391 42.2267C11.25 39.1017 13.1641 36.4845 15.8398 34.4728C16.8555 33.711 17.2656 32.7931 16.8945 31.5431C16.3281 29.7071 15.7617 27.8712 15.1953 26.0353C16.8945 26.1329 18.418 26.8556 19.5703 28.2423C20 28.7696 20.332 29.3751 20.6641 29.961C21.25 30.9767 21.9922 31.3282 23.1445 31.1915C24.6289 31.0353 26.0938 30.879 27.5781 30.8595C33.2227 30.8204 38.8477 30.8009 44.4922 30.8595C52.4805 30.9376 59.6289 36.7579 61.3867 44.5314C63.3594 53.3986 58.3984 62.1681 49.7461 65.1759Z\"><\/path><path d=\"M42.3242 1.19141C41.1914 0.644531 39.9023 0.390625 38.6719 0H36.1719C35.9961 0.0585938 35.8203 0.117188 35.625 0.15625C29.5898 1.21094 25.4297 7.10938 26.5234 13.0859C27.5976 19.0039 33.5351 23.0469 39.4922 21.9336C44.2383 21.0547 47.7148 17.3047 48.418 12.3242C49.043 7.96875 46.4648 3.16406 42.3242 1.19141ZM37.5195 17.7148C33.8476 17.7148 30.7617 14.707 30.7617 11.1133C30.7617 7.5 33.8867 4.375 37.5 4.375C41.0937 4.375 44.1016 7.46094 44.082 11.1328C44.082 14.7656 41.1133 17.7148 37.5195 17.7148Z\" fill=\"#8081FF\"><\/path><path d=\"M48.3201 38.3006C47.9685 39.1796 47.1873 39.7069 46.1326 39.7069C43.2224 39.7069 40.3318 39.7069 37.4217 39.7069C34.5701 39.7069 31.7185 39.7069 28.867 39.7069C27.3826 39.7069 26.367 38.828 26.367 37.5389C26.3474 36.2108 27.3631 35.3124 28.8865 35.3124C34.6092 35.3124 40.3514 35.3124 46.074 35.3124C47.8123 35.3124 48.9256 36.7772 48.3201 38.3006Z\"><\/path><path d=\"M21.9728 41.9141C21.9532 43.1055 20.9571 44.0821 19.7657 44.0821C18.5548 44.0821 17.5392 43.0274 17.5782 41.8165C17.6173 40.6251 18.6329 39.668 19.8243 39.6875C21.0157 39.7266 21.9923 40.7422 21.9728 41.9141Z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSecure your future today: Start your retirement plan now and live the retirement of your dreams!\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d8e3b elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d9d8e3b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visa mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-afb499d\" data-id=\"afb499d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fb5c7b elementor-position-left elementor-widget__width-initial elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"9fb5c7b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"62\" height=\"71\" viewbox=\"0 0 62 71\"><path d=\"M44.7192 34.5369H17.0109C16.779 34.5369 16.5858 34.3437 16.5858 34.1118V27.2717C16.5858 27.1171 16.6631 27.0012 16.779 26.9239L30.6525 18.9245C30.7684 18.8472 30.923 18.8472 31.0776 18.9245L44.951 26.9239C45.067 27.0012 45.1442 27.1171 45.1442 27.2717V34.1505C45.1056 34.3437 44.951 34.5369 44.7192 34.5369ZM34.0919 44.0435C34.0919 45.8212 32.6234 47.2897 30.8457 47.2897C29.0294 47.2897 27.5996 45.8212 27.5996 44.0435C27.5996 42.2659 29.0681 40.7974 30.8457 40.7974C32.662 40.7974 34.0919 42.2272 34.0919 44.0435ZM49.2792 22.9821L32.2369 13.1664C31.8118 12.9345 31.3481 12.7799 30.8457 12.7799C30.382 12.7799 29.8796 12.8959 29.4545 13.1664L12.4508 22.9821C11.6007 23.4845 11.0596 24.3734 11.0596 25.3781V45.0483C11.0596 45.7052 11.2915 46.3235 11.7166 46.8259C11.9098 47.0578 12.1803 47.2897 12.4508 47.4442L15.7743 49.3378L25.4355 54.9027L29.4931 57.26C29.9182 57.4919 30.382 57.6078 30.8844 57.6464C31.3481 57.6464 31.8505 57.5305 32.2756 57.26L36.3333 54.9027L45.9944 49.3378L49.3179 47.4442C49.5884 47.2897 49.8589 47.0578 50.0521 46.8259C50.4772 46.3235 50.7091 45.7052 50.7091 45.0483V25.3781C50.6704 24.3734 50.1294 23.4845 49.2792 22.9821ZM30.6525 63.9455L20.7208 58.2261L16.5858 55.8301L15.1946 55.0186L11.0596 52.6226L6.03582 49.7243C5.91989 49.647 5.8426 49.5311 5.8426 49.3765V21.0113C5.8426 20.8567 5.91989 20.7408 6.03582 20.6635L30.6525 6.44222C30.7684 6.36493 30.923 6.36493 31.0776 6.44222L55.6942 20.6635C55.8102 20.7408 55.8875 20.8567 55.8875 21.0113V49.4151C55.8875 49.5697 55.8102 49.6856 55.6942 49.7629L54.0712 50.6904L50.6704 52.6613L48.6609 53.8206L45.1442 55.8688L31.0776 63.9842C31.0003 64.0228 30.9616 64.0228 30.8844 64.0228C30.8071 64.0228 30.7298 63.9842 30.6525 63.9455ZM29.4931 0.722802L1.70762 16.7604C0.857432 17.2627 0.316406 18.1902 0.316406 19.1563V51.2314C0.316406 52.2362 0.857432 53.125 1.70762 53.6274L11.0596 59.0377L15.1946 61.4336L16.5858 62.2452L20.7208 64.6411L29.4545 69.6649C29.8796 69.8968 30.3433 70.0514 30.8457 70.0514C31.3094 70.0514 31.8118 69.9355 32.2369 69.6649L45.1056 62.2065L49.2406 59.8105L50.6318 58.999L54.7668 56.603L59.9838 53.5887C60.834 53.0864 61.375 52.1975 61.375 51.1928V19.1177C61.375 18.1129 60.834 17.2241 59.9838 16.7217L32.2369 0.722802C31.8118 0.490934 31.3481 0.375 30.8457 0.375C30.3433 0.375 29.9182 0.490934 29.4931 0.722802Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFutswap\u00ae protects clients' assets while growing them\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76e3a68 elementor-align-right elementor-mobile-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"76e3a68\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/depa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visa mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75cc810 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75cc810\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e40f5a\" data-id=\"4e40f5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-deef42d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"deef42d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-642f8a5\" data-id=\"642f8a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9ae865 elementor-position-left elementor-mobile-position-left elementor-widget-mobile__width-auto elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"d9ae865\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:serif=\"http:\/\/www.serif.com\/\" width=\"100%\" height=\"100%\" viewbox=\"0 0 287 326\" xml:space=\"preserve\" style=\"fill-rule:evenodd;clip-rule:evenodd;stroke-linejoin:round;stroke-miterlimit:2;\">    <g transform=\"matrix(1,0,0,1,-5055,-1616)\">        <g transform=\"matrix(1.80606,0,0,1.80606,3007.18,1086.73)\">            <path d=\"M1209.8,294.013L1137.92,335.499C1135.73,336.787 1134.34,339.149 1134.34,341.702L1134.34,424.671C1134.34,427.248 1135.73,429.61 1137.92,430.875L1162.14,444.854L1172.87,451.057L1176.45,453.107L1187.18,459.311L1209.8,472.359C1210.9,473.004 1212.14,473.313 1213.38,473.313C1214.6,473.313 1215.84,473.004 1216.96,472.359L1250.28,453.107L1261.02,446.929L1264.6,444.854L1275.33,438.651L1288.81,430.875C1291.01,429.61 1292.39,427.248 1292.39,424.671L1292.39,341.702C1292.39,339.149 1291.01,336.787 1288.81,335.499L1216.96,294.013C1215.85,293.381 1214.61,293.065 1213.37,293.065C1212.13,293.065 1210.9,293.381 1209.8,294.013ZM1212.85,457.599L1187.18,442.778L1176.45,436.576L1172.87,434.525L1162.14,428.322L1149.18,420.848C1148.86,420.659 1148.66,420.312 1148.66,419.937L1148.66,346.436C1148.66,346.06 1148.86,345.713 1149.18,345.525L1212.85,308.774C1213.18,308.587 1213.58,308.587 1213.9,308.774L1277.55,345.525C1277.88,345.713 1278.07,346.06 1278.07,346.436L1278.07,419.934C1278.07,420.311 1277.87,420.659 1277.55,420.848L1273.38,423.24L1264.6,428.322L1259.4,431.327L1250.28,436.6L1213.9,457.599C1213.74,457.692 1213.56,457.739 1213.38,457.739C1213.2,457.739 1213.01,457.692 1212.85,457.599ZM1261.02,351.554L1216.93,326.123C1215.84,325.48 1214.6,325.158 1213.37,325.157C1212.13,325.158 1210.9,325.48 1209.8,326.123L1165.71,351.554C1163.52,352.841 1162.14,355.203 1162.14,357.756L1162.14,408.64C1162.14,410.334 1162.76,411.956 1163.83,413.22C1164.35,413.866 1164.98,414.39 1165.71,414.82L1174.28,419.768C1174.29,419.774 1174.3,419.778 1174.32,419.784L1199.3,434.205L1209.8,440.273C1210.89,440.916 1212.13,441.224 1213.37,441.227C1214.6,441.224 1215.84,440.916 1216.93,440.273L1227.43,434.205L1252.42,419.784C1252.43,419.778 1252.44,419.774 1252.45,419.768L1261.02,414.82C1261.76,414.39 1262.38,413.866 1262.9,413.22C1263.98,411.956 1264.6,410.334 1264.6,408.64L1264.6,357.756C1264.6,355.203 1263.21,352.841 1261.02,351.554ZM1221.78,406.045C1221.78,410.691 1218.01,414.459 1213.37,414.459C1208.72,414.459 1204.95,410.691 1204.95,406.045C1204.95,401.397 1208.72,397.63 1213.37,397.63C1218.01,397.63 1221.78,401.397 1221.78,406.045ZM1249.23,381.476L1177.5,381.476C1176.92,381.476 1176.45,381.004 1176.45,380.423L1176.45,362.654C1176.45,362.279 1176.65,361.932 1176.98,361.743L1212.84,341.046C1213.17,340.859 1213.57,340.858 1213.89,341.046L1249.76,361.705C1250.08,361.893 1250.28,362.241 1250.28,362.617L1250.28,380.423C1250.28,381.004 1249.81,381.476 1249.23,381.476Z\" style=\"fill:rgb(20,18,64);fill-rule:nonzero;\"><\/path>        <\/g>    <\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDep\u00e5konto\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b33d86b elementor-widget elementor-widget-heading\" data-id=\"b33d86b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Skydda dina aff\u00e4rstillg\u00e5ngar medan du odlar dem. P\u00e5 f\u00f6rfr\u00e5gan<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21e40ba elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"21e40ba\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kontantins\u00e4ttningar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Digitala tillg\u00e5ngar<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lager<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e5material<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c4delmetaller<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fastighet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f745c1 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"2f745c1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/depa\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visa mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbbf5d2 elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"cbbf5d2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/login.futswap.io\/sign-up\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ans\u00f6k nu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d4ed9fe\" data-id=\"d4ed9fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac6d27b animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ac6d27b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"762\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1.png\" class=\"attachment-full size-full wp-image-463\" alt=\"V\u00e5rdnad Futswap\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1.png 762w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-300x300.png 300w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-100x100.png 100w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-600x600.png 600w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-150x150.png 150w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-12x12.png 12w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/account-custody-2-1-1-1-96x96.png 96w\" sizes=\"(max-width: 762px) 100vw, 762px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-54b6c70 e-flex e-con-boxed e-con e-parent\" data-id=\"54b6c70\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-543d924 e-con-full e-flex e-con e-child\" data-id=\"543d924\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71f3c6e elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"71f3c6e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"74\" viewbox=\"0 0 70 74\"><path d=\"M61.6488 51.8999C61.6488 52.0676 61.565 52.1934 61.4392 52.2772L59.7205 53.2413L56.1154 55.3373L53.9776 56.553L50.2467 58.6909L35.3654 67.2843C35.2396 67.3682 35.0719 67.3682 34.9462 67.2843L24.4663 61.2479L20.0648 58.6909L18.5976 57.8525L14.1961 55.3373L8.95614 52.2772C8.83038 52.1934 8.74654 52.0676 8.74654 51.8999V50.6843C10.1299 49.762 11.0521 48.1272 11.0521 46.3246C11.0521 43.4322 8.70463 41.0847 5.81219 41.0847C2.91975 41.0847 0.572266 43.4322 0.572266 46.3246C0.572266 48.1272 1.49449 49.7201 2.87783 50.6843V53.8282C2.87783 54.8762 3.4647 55.8403 4.34501 56.3434L14.238 62.0863L18.6395 64.6015L20.1067 65.4399L24.5082 67.997L33.7305 73.3207C34.1916 73.5722 34.6946 73.698 35.1977 73.698C35.7007 73.698 36.2037 73.5722 36.6649 73.3207L50.2887 65.4399L54.6902 62.9247L56.1574 62.0863L60.5589 59.5712L66.0503 56.3853C66.9726 55.8823 67.5175 54.9181 67.5175 53.8701V43.8095H61.6907V51.8999H61.6488Z\"><\/path><path d=\"M67.4747 23.185V19.9153C67.4747 18.8673 66.9298 17.9031 66.0076 17.4001L36.664 0.464665C36.2029 0.171229 35.6998 0.0454712 35.1968 0.0454712C34.6938 0.0454712 34.1907 0.171229 33.7296 0.422746L4.34413 17.4001C3.46382 17.9451 2.87695 18.9092 2.87695 19.9153V30.8981H8.70375V21.8436C8.70375 21.6759 8.78759 21.5501 8.91334 21.4663L34.9453 6.45914C35.071 6.3753 35.2387 6.3753 35.3645 6.45914L61.3964 21.4663C61.5222 21.5501 61.606 21.6759 61.606 21.8436V23.185C60.2227 24.1072 59.3004 25.7421 59.3004 27.5446C59.3004 30.437 61.6479 32.7845 64.5404 32.7845C67.4328 32.7845 69.7803 30.437 69.7803 27.5446C69.7803 25.7001 68.8581 24.1072 67.4747 23.185Z\"><\/path><path d=\"M34.107 57.7684C34.4424 57.978 34.8197 58.0618 35.1969 58.0618C35.5742 58.0618 35.9515 57.978 36.2868 57.7684C39.5985 55.8401 49.4915 50.1391 52.845 48.2108C53.5157 47.8335 53.9349 47.079 53.9349 46.3244V27.2092C53.9349 26.4127 53.5157 25.7001 52.845 25.3228C49.5334 23.3945 39.6404 17.6935 36.2868 15.7652C35.9515 15.5556 35.5742 15.4717 35.1969 15.4717C34.8197 15.4717 34.4424 15.5556 34.107 15.7652C30.7535 17.6935 20.8605 23.3945 17.5489 25.3228C16.8782 25.7001 16.459 26.4546 16.459 27.2092V46.3244C16.459 47.1209 16.8782 47.8335 17.5489 48.2108C20.8605 50.0971 30.7535 55.8401 34.107 57.7684ZM22.3277 29.3471L30.502 24.6102L35.155 21.9273C38.6763 23.9395 44.503 27.3349 48.0243 29.3471V44.1865C44.503 46.1986 38.6763 49.5941 35.155 51.6062L29.0348 48.085L22.3277 44.1865V29.3471Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOpen your Operational Account online\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d17f05e elementor-widget elementor-widget-heading\" data-id=\"d17f05e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Banktj\u00e4nster<br class=\"hide-on-mobile\"> den d\u00e4r <span style=\"color:var(--e-global-color-primary)\">anpassa sig till<br class=\"hide-on-mobile\">\nmodern v\u00e4rld<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54b93de elementor-widget elementor-widget-heading\" data-id=\"54b93de\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Maximize your financial efficiency: Open your operational account today and simplify your transactions!<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55860da e-con-full e-flex e-con e-child\" data-id=\"55860da\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b4e583 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"1b4e583\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/operational-account\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">know more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b76d1bf e-con-full e-flex e-con e-child\" data-id=\"b76d1bf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6845098 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6845098\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"595\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2025\/01\/futswap-phone-card-654.png\" class=\"attachment-full size-full wp-image-11995\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2025\/01\/futswap-phone-card-654.png 452w, https:\/\/futswap.se\/wp-content\/uploads\/2025\/01\/futswap-phone-card-654-228x300.png 228w, https:\/\/futswap.se\/wp-content\/uploads\/2025\/01\/futswap-phone-card-654-9x12.png 9w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3faffd1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3faffd1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6f955d\" data-id=\"c6f955d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-010b39f elementor-invisible elementor-widget elementor-widget-image\" data-id=\"010b39f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"415\" height=\"633\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue.png\" class=\"attachment-full size-full wp-image-11050\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue.png 415w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue-300x458.png 300w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue-197x300.png 197w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue-8x12.png 8w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/10\/futcard-blue-150x229.png 150w\" sizes=\"(max-width: 415px) 100vw, 415px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f82b3 elementor-widget elementor-widget-heading\" data-id=\"d3f82b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Futcard-program utf\u00e4rdat av financia credit och drivs av ViaCarte Inc.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b08d16e\" data-id=\"b08d16e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44769de elementor-hidden-mobile elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"44769de\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"51\" height=\"28\" viewbox=\"0 0 51 28\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0 13.251H17.6895V10.8593H0V13.251ZM45.6565 21.3093C45.6565 21.1153 45.5057 20.9645 45.3118 20.9645H32.6641C32.4702 20.9645 32.3194 21.1153 32.3194 21.3093V21.9772C32.3194 22.1711 32.4702 22.3219 32.6641 22.3219H45.3118C45.5057 22.3219 45.6565 22.1711 45.6565 21.9772V21.3093ZM10.73 0.387833L1.42205 5.75285C0.538657 6.26996 0 7.218 0 8.23067V8.46768H17.6895C18.3359 8.46768 18.9176 8.70469 19.3916 9.17871C19.8441 9.63118 20.0811 10.1914 20.0811 10.8593V23.076L22.8821 21.4601C23.7655 20.943 24.3257 19.9949 24.3257 18.9607V8.23067C24.3257 7.218 23.7871 6.26996 22.8821 5.75285L13.5957 0.366286C13.1432 0.129278 12.6692 0 12.1521 0C11.6565 0 11.161 0.129278 10.73 0.387833ZM20.4043 0.818758H48.5222C49.8796 0.818758 51 1.91762 51 3.29658V23.9163C51 25.2738 49.8796 26.3942 48.5222 26.3942H20.4043L24.3473 24.1103C26.2003 23.033 27.3422 21.0507 27.3422 18.8961V8.29531C27.3422 6.14068 26.2003 4.15843 24.3473 3.08112L20.4043 0.818758ZM0 15.6426V18.9607C0 19.9949 0.560203 20.943 1.4436 21.4385L10.73 26.8035C11.161 27.0621 11.6565 27.1914 12.1736 27.1914C12.6692 27.1914 13.1648 27.0621 13.6172 26.8035L17.711 24.4335V15.6426H0Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c24b8 elementor-widget elementor-widget-heading\" data-id=\"34c24b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beg\u00e4r ditt Futcard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e6788 elementor-widget elementor-widget-heading\" data-id=\"35e6788\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Framtidens kort<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da6835b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da6835b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-2fdcdf8\" data-id=\"2fdcdf8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3937119 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"3937119\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"120\" height=\"90\" viewbox=\"0 0 120 90\"><path d=\"M18.4615 57.666C14.7692 57.666 11.0769 55.7438 9.84615 52.5402H18.4615V49.3365H8.61539C8.61539 48.6958 8.61539 48.0551 8.61539 47.4143C8.61539 46.7736 8.61539 46.1329 8.61539 45.4921H18.4615V42.9292H9.84615C11.0769 39.0848 14.7692 37.1626 18.4615 37.1626C20.9231 37.1626 23.3846 37.8033 25.2308 39.7255L27.6923 37.1626C25.2308 34.5997 22.1538 32.6775 18.4615 32.6775C12.3077 32.6775 7.38462 36.5219 5.53846 42.2885H0V45.4921H4.92308C4.92308 46.1329 4.92308 46.7736 4.92308 47.4143C4.92308 48.0551 4.92308 48.6958 4.92308 49.3365H0V52.5402H5.53846C7.38462 57.666 12.3077 62.1512 18.4615 62.1512C22.1538 62.1512 25.2308 60.8697 27.6923 58.3068L25.2308 55.1031C23.3846 57.0253 20.9231 57.666 18.4615 57.666Z\" fill=\"#8081FF\"><\/path><path d=\"M62.1543 39.0847C51.6927 35.881 48.0004 32.6773 48.0004 28.1922C48.0004 23.0664 52.9235 19.222 60.9235 19.222C69.5389 19.222 72.6158 23.7071 72.6158 29.4737H83.0773C82.462 21.1442 77.5389 13.4554 67.6927 10.8924V0H53.5389V10.8924C44.3081 12.8146 36.9235 19.222 36.9235 28.1922C36.9235 39.7254 46.1543 45.492 59.0773 48.6956C70.7696 51.8993 73.2312 55.7437 73.2312 60.8696C73.2312 64.0732 70.7696 69.8398 60.3081 69.8398C50.462 69.8398 46.7696 65.3547 46.1543 59.5881H36.3081C36.9235 70.4805 44.9235 76.2471 53.5389 78.1693V89.0618H67.6927V78.1693C76.9235 76.2471 84.3081 70.4805 84.3081 60.8696C84.3081 46.7734 72.6158 41.6476 62.1543 39.0847Z\"><\/path><path d=\"M113.231 64.7143C116.308 64.7143 119.385 62.7921 120 59.5885L116.923 57.6663C116.308 59.5885 115.077 60.8699 113.231 60.8699H104.615C105.846 58.9477 107.077 56.3848 107.077 53.8219C107.077 53.1811 107.077 52.5404 107.077 51.8997H113.231V48.696H105.846C104.615 46.1331 102.769 44.2109 102.769 41.648C102.769 38.4443 105.231 35.2406 108.923 35.2406C111.385 35.2406 113.846 37.1628 114.462 39.085L117.539 37.8036C116.308 33.9592 112.615 31.3962 108.923 31.3962C104 31.3962 99.6924 35.8814 99.6924 41.0072C99.6924 44.2109 100.923 46.1331 102.154 48.0553H99.6924V51.8997H104C104 52.5404 104 53.1811 104 53.8219C104 58.9477 99.6924 60.8699 99.6924 60.8699V64.7143H113.231Z\" fill=\"#8081FF\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tM\u00f6jlighet att ladda fr\u00e5n olika konton\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-e607dbe\" data-id=\"e607dbe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5287b71 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5287b71\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<path d=\"M376.4,36.8l-182.6-0.1c-10.7,0-19.3,8.6-19.3,19.3v0h0v103.2v12.9v24.6v2c-0.6,8.1-4.3,32.2-13.9,39    c-13.2,9.5-25.2,21-37.1,32.3c-7.7,7.4-11.8,17.1-11.4,28.1c0.6,18.7,0.9,37.5,2.7,56.2c3.2,32.5,8.6,64.8,16.2,96.6    c0.4,1.3-0.6,3.7-1.6,4.4c-1.3,0.8-2.5,1.8-3.6,2.7c-7,6-2.8,17.4,6.3,17.4h191.5c8.9,0,13.4-11.1,6.7-17.1    c-3.4-3-7.7-5.3-12.9-6.8c-0.2-0.1-0.4-0.1-0.6-0.2c-1-0.3-1.3-1.6-0.7-2.4c16.8-20.4,22-44.9,24.5-70.3c0.1-0.8,0.7-1.4,1.5-1.4    h18.8c24.1-0.1,39.2-15.2,39.2-39.4c0-5.2,0-13.3,0-23.5c0-32.8,0-87.6,0-139.8c0-3.2-3.5-5.2-6.3-3.5    c-5.4,3.4-12.9,8.4-16.3,10.6c-1.1,0.8-1.8,2-1.8,3.4l0,15.4v0.1v0.3h0c0.1,32.3,0.1,77.7,0.2,113.4c0,9,0,17.4,0,24.8    c0,8.8-3.9,13.3-11.8,13.9c0,0-0.1,0-0.1,0h-92.1c-1.4,0-2-1.7-1-2.6c3-2.8,5.6-5.3,8.3-7.8c6.1-5.5,10.4-12.2,12.7-20.1    c4.6-16.2-0.5-30-14.5-39.3c-4.9-3.2-9.9-5.6-15-7v-215h105.3c4.6,0,8.3,3.7,8.3,8.3l0,28.7l0,6.2l0,18l0,6.1c0,3,3.2,5,5.9,3.7    c5.2-2.6,12.6-6.4,16.2-8.3c1.4-0.7,2.2-2.1,2.2-3.6c0-5.4,0-10.7,0-15.8c0-17.2,0-32.2,0-43.7C400.1,47.4,389.5,36.8,376.4,36.8z     M268.6,315.5c-1.5,3.6-3.9,7-6.5,9.9c-8.4,9.1-17.5,17.6-25.8,26.9c-8.4,9.5-11.6,21.3-12.5,33.8c-0.5,7.4,3.9,12.9,10.5,13.5    c7,0.6,12.5-3.9,13.5-11.3c1.6-10.9,1.6-10.9,12.4-10.9h54.2c0.9,0,1.6,0.7,1.5,1.6c-1.5,20.5-5.2,39.6-19.2,55.2    c-9.9,11.1-22.7,16.2-37.2,16.4c-34.2,0.4-68.4,0.1-102.7,0.1c-0.2,0-0.4-0.1-1-0.2c-0.5-0.2-0.9-0.6-1-1.1    c-2.4-12.1-5.5-24.5-7.3-37c-4.2-30.1-8.1-60.1-11.6-90.3c-1-7.9-0.8-16.1,0-24.1c0.4-4,2.3-8.8,5.1-11.6    c10-9.9,20.6-19.2,31-28.8c0.4-0.4,1.1-0.5,1.6-0.3l0,0c0.5,0.2,0.9,0.8,0.9,1.4v4.2c0,20.5-0.1,41,0.1,61.4    c0.1,3.9-1.2,6.8-3.4,10.1c-2.2,3.1-4,7.1-4.2,10.8c-0.1,5.1,3.2,8.6,8.2,10.2c5.1,1.6,9.4,0,12.7-3.8c4-4.4,7.7-9.3,11.8-13.7    c11.5-12.7,23.9-24.4,38.6-33.7c8.6-5.4,17.1-7.3,26.1-0.8C269.2,307,270.9,310,268.6,315.5z M237.9,277.5    c-1.8,0.7-3.5,1.5-5.3,2.5c-9.4,5.3-18,12-27,18.2c-1.4,1-2.6,2.1-4,3.4c-1,0.9-2.5,0.2-2.5-1.1v-99.7h0v-40.8V67.7    c0-3.7,3-6.6,6.6-6.6h32.2V277.5z\"><\/path>\t\t<path d=\"M331.5,78.8c-3,0-5.4,2.1-5.4,4.8v66.7c0,2.6,2.4,4.8,5.4,4.8h9.4c3,0,5.4-2.1,5.4-4.8V83.6    c0-2.6-2.4-4.8-5.4-4.8H331.5z\"><\/path>\t<\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPurchase in physical establishments or purchase online\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-737f278\" data-id=\"737f278\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13367a6 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"13367a6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<path d=\"M461.1,136c-0.1-3.2-0.5-6.5-1.4-9.5c-4.2-14.2-16.2-22.5-32.4-22.5c-53.5,0-107.1,0-160.6,0   c-1.9,0-3,2.2-1.9,3.7l11.5,16.4c0.4,0.6,1.2,1,1.9,1c49.2,0,98.5,0,147.7,0c1.3,0,2.6,0,4,0.1c6.1,0.5,10.1,4.4,10.2,10.5   c0.2,7.6,0.2,15.2,0,22.8c-0.1,5.4-3.5,9.9-8.5,10.1c-3.1,0.1-6.1,0.2-9.2,0.2c-1.6,0-3,1.3-3,3v14.8c0,1.6,1.3,3,3,3   c2.2,0,4.4,0,6.7-0.1c18.9-0.4,32.1-14,32.2-32.8C461.2,149.7,461.3,142.9,461.1,136z M343.9,157.9c-5-0.1-10.5,0-16.5,0   c3.3,5.5,5.1,11.9,5.1,18.8c0,20.6-16.7,37.3-37.3,37.3c-20.6,0-37.3-16.7-37.3-37.3c0-6.8,1.8-13.2,5-18.6h-16.5   c-2.2,5.8-3.4,12.1-3.4,18.6c0,28.9,23.4,52.3,52.3,52.3s52.3-23.4,52.3-52.3C347.4,170.1,346.2,163.8,343.9,157.9z\"><\/path>\t<path d=\"M403.1,136.5c-1.6-0.1-3.3-0.1-4.9-0.1c0,0-28.1,0-63.7,0H268c-36.8,0-69.1,0-76.3,0.1c-2.2,0-4.4,0-6.5,0.3   c-5.3,0.8-8.9,5.2-8.9,10.5c0.1,5.2,3.9,9.5,9.2,10.1c3.4,0.3,7,0.1,10.9,0.1v11.3c-1.2,0.2-2.3,0.4-3.4,0.4   c-10.1,0-20.2,0.1-30.3,0c-9-0.1-12.7-3.9-12.8-12.9c0-6.5-0.1-12.9,0-19.3c0.1-7.4,4-11.4,11.3-11.7c1-0.1,2.1-0.1,3.1-0.1h73.8   c1.8,0,3-1.9,2.1-3.5l-8.9-16.4c-0.4-0.7-1.2-1.2-2.1-1.2h-66.5c-1.5,0-3,0.1-4.4,0.2c-16.2,1.1-28.9,14.2-29.3,30.6   c-0.2,8.2-0.3,16.4,0.1,24.6c0.6,13.2,7,22.9,19.1,28c4.7,2,10.3,2.5,15.4,2.6c10.8,0.4,21.7,0.1,33,0.1c0,4.1-3,29.2-12.2,35.8   c-11.6,8.3-22,18.3-32.4,28.2c-6.8,6.5-10.3,14.9-10,24.5c0.6,16.4,0.8,32.8,2.4,49.1c2.8,28.4,7.5,56.6,14.1,84.4   c0.3,1.1-0.5,3.2-1.4,3.8c-1.2,0.7-2.2,1.5-3.1,2.3c-6.1,5.2-2.5,15.2,5.5,15.2h167.3c7.8,0,11.7-9.7,5.8-14.9   c-3-2.6-6.7-4.6-11.3-6c-0.7-0.2-1.4-0.5-2.3-0.8c15.9-18.5,20.5-40.8,22.7-64h17.6c21-0.1,34.2-13.3,34.3-34.4   c0-39.4,0.1-155.9,0.1-155.9c3.2,0,6.2,0.1,9.3,0c6.4-0.3,10.7-4.5,10.8-10.4C413.7,141.2,409.5,137,403.1,136.5z M303.3,397.6   c-8.6,9.7-19.9,14.1-32.5,14.3c-29.9,0.4-59.8,0.1-89.7,0.1c-0.2,0-0.6-0.1-1.6-0.4c-2.2-10.8-4.9-21.9-6.5-33.1   c-3.7-26.3-7.1-52.5-10.1-78.9c-0.9-6.9-0.7-14,0-21c0.4-3.5,2-7.7,4.4-10.1c8.9-8.9,18.5-17.2,27.7-25.7c0.8,0.3,0.9,0.4,1.6,0.7   v4.6c0,17.9-0.1,35.8,0.1,53.6c0.1,3.4-1,6-3,8.8c-1.9,2.7-3.5,6.2-3.6,9.4c-0.1,4.4,2.8,7.5,7.2,8.9c4.5,1.4,8.2,0,11.1-3.3   c3.5-3.9,6.7-8.1,10.3-12c10.1-11.1,20.9-21.3,33.7-29.4c7.5-4.7,14.9-6.4,22.8-0.7c4.2,3.1,5.6,5.7,3.6,10.5   c-1.3,3.1-3.4,6.2-5.7,8.6c-7.4,7.9-15.3,15.4-22.5,23.5c-7.4,8.3-10.1,18.6-10.9,29.5c-0.4,6.5,3.4,11.3,9.2,11.8   c6.2,0.6,10.9-3.4,11.8-9.8c1.4-9.5,1.4-9.5,10.8-9.5h48.7C318.8,366.4,315.7,383.7,303.3,397.6z M372.3,314.5   c0,7.7-3.4,11.6-10.3,12.1h-83.8c3.6-3.4,6.6-6.3,9.7-9.1c5.4-4.8,9.1-10.6,11.1-17.6c4.1-14.1-0.4-26.2-12.7-34.3   c-12.5-8.2-25.7-10-39-2.7c-8.2,4.6-15.7,10.5-23.6,15.9c-1.9,1.4-3.5,3.1-5.7,5V158.2c7.1,0,19.6,0,34.5-0.1H269   c21.4-0.1,45.2-0.1,64.5-0.2c6,0,11.6-0.1,16.5,0c13.3-0.1,22-0.1,22-0.1C372.1,159.1,372.4,263.5,372.3,314.5z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTa ut pengar i vilken bankomat som helst i v\u00e4rlden\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-f8393b3\" data-id=\"f8393b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6ec845 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c6ec845\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<path d=\"M308,284.6c1.7,1,4-0.2,4-2.2v-44.2c0-3.2-1.7-6.2-4.5-7.8l-55.2-31.9c-2.8-1.6-6.2-1.6-9,0L188,230.4   c-2.7,1.6-4.5,4.6-4.5,7.8V302c0,2.1,0.8,4.2,2.1,5.7c0.6,0.8,1.4,1.5,2.3,2l10.7,6.2c2.3,1.3,5.1,1.3,7.4,0l14.2-8.2l26.8-15.4   c0.4-0.2,0.8-0.2,1.2,0l24.4,14.1c1.1,0.6,1.1,2.1,0,2.7L254,319.9c-3.9,2.2-8.6,2.2-12.5,0l-0.5-0.3c-1.7-1-3.7-1-5.4,0l-10.8,6.2   c-2,1.1-2,4,0,5.2l18.4,10.6c1.4,0.8,2.9,1.2,4.5,1.2c1.5,0,3.1-0.4,4.5-1.2l51.4-30.5c2.9-1.7,2.9-6-0.1-7.7l-10.5-6.1l-11.1-6.4   l-4.9-2.9l-24.8-14.3c-2.8-1.6-6.2-1.6-9,0l-41,22.8c-0.6,0.3-1.4-0.1-1.3-0.8l0.6-51.8c0-0.4,0.2-0.8,0.6-1l45.1-26   c0.4-0.2,0.8-0.2,1.2,0l45.1,26c0.4,0.2,0.6,0.6,0.6,1v29.9c0,1.4,0.8,2.8,2,3.5L308,284.6z\"><\/path>\t<path d=\"M249.9,140.3c-15.8-0.3-30.9,2.3-44.9,7.2c-2.6,0.9-3.7,3.9-2.5,6.3l7.6,14.7c1,2,3.3,2.9,5.4,2.2   c10.1-3.3,21-5.1,32.2-5.1c57.7,0,104.6,47.1,104.3,104.8c-0.3,57.7-47.3,104.2-105.2,103.8c-57.2-0.5-103.8-47.7-103.4-104.9   c0.2-35,17.7-65.9,44.3-84.7c1.9-1.4,2.5-4,1.3-6l-8.5-14.1c-1.3-2.2-4.3-2.9-6.4-1.4c-34.5,23.8-56.9,63.9-56.1,109.1   c1.2,70.4,59.2,127.4,129.6,127.4c71.7,0,129.8-58,129.8-129.7C377.5,199.2,320.6,141.4,249.9,140.3z\"><\/path>\t<path d=\"M410,277.4v-9.5c0-3.7,3-6.6,6.6-6.6h27.5c3.7,0,6.6,3,6.6,6.6v9.5c0,3.7-3,6.6-6.6,6.6h-27.5   C413,284,410,281,410,277.4z\"><\/path>\t<path d=\"M404.1,219.5l-3.7-8.8c-1.4-3.4,0.2-7.3,3.5-8.7l68.5-27.9c3.4-1.4,7.3,0.2,8.7,3.5l3.7,8.8   c1.4,3.4-0.2,7.3-3.5,8.7L412.8,223C409.4,224.4,405.5,222.9,404.1,219.5z\"><\/path>\t<path d=\"M372.7,163.1l-6.8-6.8c-2.6-2.6-2.6-6.8,0-9.4l19.4-19.4c2.6-2.6,6.8-2.6,9.4,0l6.8,6.8c2.6,2.6,2.6,6.8,0,9.4   l-19.4,19.4C379.5,165.6,375.3,165.6,372.7,163.1z\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGet Rewards for more recharges\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-4c3a1ae\" data-id=\"4c3a1ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3986636 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"3986636\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"45\" height=\"45\" viewbox=\"0 0 45 45\"><path d=\"M24.5712 34.5965L32.3189 26.8488C32.7247 26.443 33.0199 25.991 33.2043 25.4929C33.3888 24.9949 33.481 24.4692 33.481 23.9157C33.481 22.7351 33.066 21.7298 32.2359 20.8997C31.4058 20.0696 30.4004 19.6545 29.2198 19.6545C28.4819 19.6545 27.7441 19.8943 27.0062 20.3739C26.2683 20.8536 25.4567 21.6283 24.5712 22.6982C23.6858 21.6283 22.8741 20.8536 22.1362 20.3739C21.3984 19.8943 20.6605 19.6545 19.9226 19.6545C18.742 19.6545 17.7367 20.0696 16.9065 20.8997C16.0764 21.7298 15.6614 22.7351 15.6614 23.9157C15.6614 24.4692 15.7536 24.9949 15.9381 25.4929C16.1226 25.991 16.4177 26.443 16.8235 26.8488L24.5712 34.5965ZM26.5081 43.7277C25.844 44.3918 25.0416 44.7238 24.1008 44.7238C23.16 44.7238 22.3576 44.3918 21.6935 43.7277L0.94079 22.975C0.571853 22.606 0.32282 22.2186 0.193692 21.8128C0.0645642 21.407 0 20.9827 0 20.54V3.71643C0 2.75719 0.313596 1.96398 0.94079 1.33679C1.56798 0.709593 2.3612 0.395996 3.32043 0.395996H20.144C20.5867 0.395996 21.0294 0.46056 21.4721 0.589688C21.9149 0.718816 22.3207 0.967849 22.6896 1.33679L43.3317 21.9788C44.0327 22.6798 44.3831 23.5007 44.3831 24.4415C44.3831 25.3823 44.0327 26.2032 43.3317 26.9041L26.5081 43.7277ZM24.2392 41.4587L41.0627 24.6352L20.144 3.71643H3.32043V20.54L24.2392 41.4587ZM9.13119 12.3496C9.90596 12.3496 10.5793 12.0636 11.1511 11.4918C11.723 10.9199 12.0089 10.2466 12.0089 9.47185C12.0089 8.69708 11.723 8.02377 11.1511 7.45192C10.5793 6.88007 9.90596 6.59414 9.13119 6.59414C8.35643 6.59414 7.68312 6.88007 7.11126 7.45192C6.53941 8.02377 6.25348 8.69708 6.25348 9.47185C6.25348 10.2466 6.53941 10.9199 7.11126 11.4918C7.68312 12.0636 8.35643 12.3496 9.13119 12.3496Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tExklusiva f\u00f6rm\u00e5ner\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-inner-column elementor-element elementor-element-a61eedb\" data-id=\"a61eedb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e81a507 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e81a507\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/futswap.se\/sv\/fotbollskort\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mer om Futcard<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-802f6b0 elementor-widget elementor-widget-text-editor\" data-id=\"802f6b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000080;\">\u2191<\/span><br \/>Om du \u00e4r kund hos n\u00e5gon Futswap\u00ae-produkt kan du beg\u00e4ra ditt Futcard.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84ea54b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84ea54b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59a191a\" data-id=\"59a191a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-424f513 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"424f513\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-df6fcf8\" data-id=\"df6fcf8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bc2d5a elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"4bc2d5a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-piggy-bank\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPensionering<br class=\"hide-on-mobile\"> konto <span class=\"text-comingsoon\">(Kommer snart)<\/span>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a7d15b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4a7d15b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Konton i EUR, SEK, USD, AED eller GBP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Konto i BTC, USDT eller ETH<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5, 10, 20 \u00e5rsplaner<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stabil juridisk ram<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Skydd av tillg\u00e5ng<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anpassade investeringsstrategier<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Skatteeffektivitet<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Professionell och expertledning<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7bc554 elementor-align-left elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"a7bc554\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/login.futswap.io\/sign-up\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beg\u00e4r konto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6980e18 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6980e18\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:fernando.londono@futswap.io?cc=manager@futswap.io\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakta en r\u00e5dgivare<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-990ce2e\" data-id=\"990ce2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acbc432 elementor-widget elementor-widget-image\" data-id=\"acbc432\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"527\" height=\"519\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop.jpg\" class=\"attachment-full size-full wp-image-9884\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop.jpg 527w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop-300x295.jpg 300w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop-12x12.jpg 12w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop-96x96.jpg 96w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-cuenta-ahorros-mujer-sentada-laptop-150x148.jpg 150w\" sizes=\"(max-width: 527px) 100vw, 527px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d1fa43c elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d1fa43c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-85737bf\" data-id=\"85737bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deba971 elementor-widget elementor-widget-image\" data-id=\"deba971\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"527\" height=\"519\" src=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust.jpg\" class=\"attachment-full size-full wp-image-9883\" alt=\"\" srcset=\"https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust.jpg 527w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust-300x295.jpg 300w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust-12x12.jpg 12w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust-96x96.jpg 96w, https:\/\/futswap.se\/wp-content\/uploads\/2022\/08\/img-personas-laptop-lendindtrust-150x148.jpg 150w\" sizes=\"(max-width: 527px) 100vw, 527px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-383cdec\" data-id=\"383cdec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caac9c5 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"caac9c5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-credit-card\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUtl\u00e5ning Trust <span class=\"text-comingsoon\">(Kommer snart)<\/span>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff94a81 elementor-widget elementor-widget-text-editor\" data-id=\"ff94a81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c4r du intresserad av att tj\u00e4na fast avkastning med en tidsins\u00e4ttning samtidigt som du kan njuta av flexibiliteten med en 75%-kredit p\u00e5 din investering genom ett hybridkort?<\/p><p>Uppt\u00e4ck hur v\u00e5r innovativa produkt kan f\u00f6rb\u00e4ttra din personliga och f\u00f6retagsekonomi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d6cf6b elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6d6cf6b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:fernando.londono@futswap.io?cc=manager@futswap.io\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakta en r\u00e5dgivare<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-553f76e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"553f76e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-713b2a4\" data-id=\"713b2a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c004e7 elementor-cta--skin-cover elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"3c004e7\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/futswap.se\/wp-content\/uploads\/2023\/12\/banner-blog-pedir-futcard-v2.jpg);\" role=\"img\" aria-label=\"banner-blogg-pedir-futcard-v2\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tHybridkort f\u00f6r f\u00f6retagsprogram\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tVill du ha ett eget program f\u00f6r kunder och\/eller anst\u00e4llda?\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"mailto:fernando.londono@futswap.io?cc=manager@futswap.io\">\n\t\t\t\t\t\tKontakta en r\u00e5dgivare\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Smarta finansiella l\u00f6sningar f\u00f6r dig att flytta dina tillg\u00e5ngar runt om i v\u00e4rlden En plattform designad<\/p>","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-392","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/pages\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/comments?post=392"}],"version-history":[{"count":10,"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/pages\/392\/revisions"}],"predecessor-version":[{"id":12281,"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/pages\/392\/revisions\/12281"}],"wp:attachment":[{"href":"https:\/\/futswap.se\/sv\/wp-json\/wp\/v2\/media?parent=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}